{"id":222,"date":"2018-02-14T14:47:36","date_gmt":"2018-02-14T14:47:36","guid":{"rendered":"http:\/\/addispace.ipleiria.pt\/?post_type=portfolio&#038;p=222"},"modified":"2018-09-03T16:21:15","modified_gmt":"2018-09-03T16:21:15","slug":"aimen","status":"publish","type":"portfolio","link":"https:\/\/addispace.ipleiria.pt\/en\/portfolio\/aimen\/","title":{"rendered":"AIMEN"},"content":{"rendered":"<table width=\"720\">\n<tbody>\n<tr>\n<td width=\"222\"><strong>Name of organisation in original language<\/strong><\/td>\n<td width=\"499\">AIMEN<\/td>\n<\/tr>\n<tr>\n<td width=\"222\"><strong>Postal address<\/strong><\/td>\n<td width=\"499\">Pol\u00edgono Industrial de Cataboi SUR-PPI-2 (Sector 2) Parcela 3 36418 O Porri\u00f1o (Pontevedra)<\/td>\n<\/tr>\n<tr>\n<td width=\"222\"><strong>Country<\/strong><\/td>\n<td width=\"499\">SPAIN<\/td>\n<\/tr>\n<tr>\n<td width=\"222\"><strong>Website<\/strong><\/td>\n<td width=\"499\"><a href=\"http:\/\/www.aimen.es\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.aimen.es\/<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"222\"><strong>Contact e-mail<\/strong><\/td>\n<td width=\"499\">aimen@aimen.es<\/td>\n<\/tr>\n<tr>\n<td width=\"222\"><strong>Category<\/strong><\/td>\n<td width=\"499\">Consulting<\/td>\n<\/tr>\n<tr>\n<td width=\"222\"><strong>Activity description <\/strong><\/td>\n<td width=\"499\">AIMEN is a private non-profit association incorporated in Vigo in 1967, on the initiative of a group of business people from Galicia. Currently, as a Centre for Innovation and Technology, we are highly specialised in advanced manufacturing technologies and materials, especially welding and bonding technologies, material processing laser technologies (cutting, surface treatment, cladding and additive manufacturing), robotics and automation.<br \/>\nAIMEN has additive manufacturing equipment, specifically with direct metal filler technology, both in powder and wire, and it participates in different projects related to this technology.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\n<div class=\"panel-group kt-accordion\" id=\"accordionname472\"><div class=\"panel panel-default panel-even\"><div class=\"panel-heading\"><a class=\"accordion-toggle collapsed\" data-toggle=\"collapse\" data-parent=\"#accordionname472\" href=\"#collapse4720\"><h5><i class=\"icon-minus kt-icon-minus primary-color\"><\/i><i class=\"icon-plus kt-icon-plus\"><\/i>Images<\/h5><\/a><\/div><div id=\"collapse4720\" class=\"panel-collapse collapse \"><div class=\"panel-body postclass\">\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-224 size-full\" src=\"http:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03.jpg\" alt=\"\" width=\"2400\" height=\"1600\" srcset=\"https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03.jpg 2400w, https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03-300x200.jpg 300w, https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03-768x512.jpg 768w, https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03-1024x683.jpg 1024w, https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03-720x480.jpg 720w\" sizes=\"auto, (max-width: 2400px) 100vw, 2400px\" \/><br \/>\n<\/div><\/div><\/div><\/div>\n\n<p>&nbsp;","protected":false},"excerpt":{"rendered":"<p>Name of organisation in original language AIMEN Postal address Pol\u00edgono Industrial de Cataboi SUR-PPI-2 (Sector 2) Parcela 3 36418 O Porri\u00f1o (Pontevedra) Country SPAIN Website http:\/\/www.aimen.es\/ Contact e-mail aimen@aimen.es Category Consulting Activity description AIMEN is a private non-profit association incorporated &hellip; <a class=\"kt-excerpt-readmore more-link\" href=\"https:\/\/addispace.ipleiria.pt\/en\/portfolio\/aimen\/\">Read More<\/a><\/p>\n","protected":false},"author":3139,"featured_media":223,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"portfolio-type":[69629,69436],"class_list":["post-222","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-type-consulting","portfolio-type-spanish"],"_links":{"self":[{"href":"https:\/\/addispace.ipleiria.pt\/en\/wp-json\/wp\/v2\/portfolio\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addispace.ipleiria.pt\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/addispace.ipleiria.pt\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/addispace.ipleiria.pt\/en\/wp-json\/wp\/v2\/users\/3139"}],"replies":[{"embeddable":true,"href":"https:\/\/addispace.ipleiria.pt\/en\/wp-json\/wp\/v2\/comments?post=222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/addispace.ipleiria.pt\/en\/wp-json\/wp\/v2\/media\/223"}],"wp:attachment":[{"href":"https:\/\/addispace.ipleiria.pt\/en\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"portfolio-type","embeddable":true,"href":"https:\/\/addispace.ipleiria.pt\/en\/wp-json\/wp\/v2\/portfolio-type?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}