{"id":222,"date":"2018-02-14T14:47:36","date_gmt":"2018-02-14T14:47:36","guid":{"rendered":"http:\/\/addispace.ipleiria.pt\/?post_type=portfolio&#038;p=222"},"modified":"2018-09-03T16:21:15","modified_gmt":"2018-09-03T16:21:15","slug":"aimen","status":"publish","type":"portfolio","link":"https:\/\/addispace.ipleiria.pt\/fr\/portfolio\/aimen\/","title":{"rendered":"AIMEN"},"content":{"rendered":"<table width=\"720\">\n<tbody>\n<tr>\n<td width=\"173\"><strong>Nom de l\u2019organisation dans la langue d\u2019origine<\/strong><\/td>\n<td width=\"389\">AIMEN<\/td>\n<\/tr>\n<tr>\n<td width=\"173\"><strong>Adresse postale<\/strong><\/td>\n<td width=\"389\">Pol\u00edgono Industrial de Cataboi SUR-PPI-2 (Sector 2) Parcela 3 36418 O Porri\u00f1o (Pontevedra)<\/td>\n<\/tr>\n<tr>\n<td width=\"173\"><strong>Pays<\/strong><\/td>\n<td width=\"389\">ESPAGNE<\/td>\n<\/tr>\n<tr>\n<td width=\"173\"><strong>Site Web<\/strong><\/td>\n<td width=\"389\">http:\/\/www.aimen.es\/<\/td>\n<\/tr>\n<tr>\n<td width=\"173\"><strong>Contact e-mail<\/strong><\/td>\n<td width=\"389\">aimen@aimen.es<\/td>\n<\/tr>\n<tr>\n<td width=\"173\"><strong>Cat\u00e9gorie<\/strong><\/td>\n<td width=\"389\">Consulteur<\/td>\n<\/tr>\n<tr>\n<td width=\"173\"><strong>Description de l\u2019activit\u00e9<\/strong><\/td>\n<td width=\"389\">AIMEN est une association priv\u00e9e \u00e0 but non lucratif fond\u00e9e \u00e0 Vigo en\u00a01967 \u00e0 l&rsquo;initiative d&rsquo;un groupe d&rsquo;entrepreneurs de Galice. Actuellement centre d&rsquo;innovation et de technologie, nous sommes hautement sp\u00e9cialis\u00e9s dans les technologies et les mat\u00e9riaux de fabrication avanc\u00e9e, notamment dans les technologies de soudure et d&rsquo;encollage, les technologies laser de traitement des mat\u00e9riaux (d\u00e9coupe, traitement de surface, gainage et fabrication additive), la robotique et l&rsquo;automobile. AIMEN poss\u00e8de un \u00e9quipement de fabrication additive, notamment la technologie de m\u00e9tal d&rsquo;apport direct, avec poudre et fil, et participe \u00e0 diff\u00e9rents projets li\u00e9s \u00e0 cette technologie.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\n<div class=\"panel-group kt-accordion\" id=\"accordionname548\"><div class=\"panel panel-default panel-even\"><div class=\"panel-heading\"><a class=\"accordion-toggle collapsed\" data-toggle=\"collapse\" data-parent=\"#accordionname548\" href=\"#collapse5480\"><h5><i class=\"icon-minus kt-icon-minus primary-color\"><\/i><i class=\"icon-plus kt-icon-plus\"><\/i>Images<\/h5><\/a><\/div><div id=\"collapse5480\" class=\"panel-collapse collapse \"><div class=\"panel-body postclass\">\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-224 size-full\" src=\"http:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03.jpg\" alt=\"\" width=\"2400\" height=\"1600\" srcset=\"https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03.jpg 2400w, https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03-300x200.jpg 300w, https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03-768x512.jpg 768w, https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03-1024x683.jpg 1024w, https:\/\/addispace.ipleiria.pt\/files\/2018\/02\/Itziar-Oyarzabal-Aimen03-720x480.jpg 720w\" sizes=\"auto, (max-width: 2400px) 100vw, 2400px\" \/><br \/>\n<\/div><\/div><\/div><\/div>\n\n<p>&nbsp;","protected":false},"excerpt":{"rendered":"<p>Nom de l\u2019organisation dans la langue d\u2019origine AIMEN Adresse postale Pol\u00edgono Industrial de Cataboi SUR-PPI-2 (Sector 2) Parcela 3 36418 O Porri\u00f1o (Pontevedra) Pays ESPAGNE Site Web http:\/\/www.aimen.es\/ Contact e-mail aimen@aimen.es Cat\u00e9gorie Consulteur Description de l\u2019activit\u00e9 AIMEN est une association &hellip; <a class=\"kt-excerpt-readmore more-link\" href=\"https:\/\/addispace.ipleiria.pt\/fr\/portfolio\/aimen\/\">Read More<\/a><\/p>\n","protected":false},"author":3139,"featured_media":223,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"portfolio-type":[69629,69436],"class_list":["post-222","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-type-consulting","portfolio-type-spanish"],"_links":{"self":[{"href":"https:\/\/addispace.ipleiria.pt\/fr\/wp-json\/wp\/v2\/portfolio\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addispace.ipleiria.pt\/fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/addispace.ipleiria.pt\/fr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/addispace.ipleiria.pt\/fr\/wp-json\/wp\/v2\/users\/3139"}],"replies":[{"embeddable":true,"href":"https:\/\/addispace.ipleiria.pt\/fr\/wp-json\/wp\/v2\/comments?post=222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/addispace.ipleiria.pt\/fr\/wp-json\/wp\/v2\/media\/223"}],"wp:attachment":[{"href":"https:\/\/addispace.ipleiria.pt\/fr\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"portfolio-type","embeddable":true,"href":"https:\/\/addispace.ipleiria.pt\/fr\/wp-json\/wp\/v2\/portfolio-type?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}